{"id":2158,"date":"2019-03-03T23:45:39","date_gmt":"2019-03-03T22:45:39","guid":{"rendered":"http:\/\/www.aipob-biodanza.org\/?p=2158"},"modified":"2019-03-03T23:45:39","modified_gmt":"2019-03-03T22:45:39","slug":"biodanza-3","status":"publish","type":"post","link":"https:\/\/www.aipob-biodanza.org\/it_IT\/biodanza-3\/","title":{"rendered":"Biodanza"},"content":{"rendered":"<h1>Biodanza &#8211; corso settimanale<\/h1>\n<p><strong>Biodanza<\/strong>. \u00c8 il sistema ideato dallo psicologo, antropologo e poeta cileno <a href=\"http:\/\/www.aipob-biodanza.org\/it_IT\/rolando-toro\/\">Rolando Toro.<\/a><\/p>\n<p>Utilizzando la musica e il movimento, favorisce l\u2019integrazione, aiutando a\u00a0 stimolare lo sviluppo dei potenziali ancora inespressi e risvegliando la gioia di vivere.<\/p>\n<p>Ogni sessione di <em>Biodanza<\/em> si compone di un insieme di esercizi e di musiche organizzati\u00a0 secondo un\u00a0 modello teorico destinato ad elevare il grado di salute.<\/p>\n<p>Inoltre, la Biodanza aiuta a\u00a0 migliorare la comunicativit\u00e0 e infine stimolare la creativit\u00e0 non solo artistica ma anche come capacit\u00e0 di rinnovamento esistenziale.<\/p>\n<p>Degno di nota \u00e8 il fatto che ogni partecipante \u00e8 invitato a scoprire le proprie risposte vitali e a scegliere forme di espressione e di azione che rinforzino il proprio sviluppo armonico ed equilibrato.<\/p>\n<p>Non \u00e8 necessario saper danzare, quindi occorre solo sentire il desiderio di divertirsi e rinnovarsi.<\/p>\n<p>\u00c8 anche\u00a0 soprattutto un modo di avvicinarsi agli altri e aprirsi a nuovi incontri, di conseguenza migliorare il proprio stato di benessere e aumentare la gioia di vivere<\/p>\n<h5>Dalla leggerezza dell\u2019aria all\u2019intensit\u00e0 avvolgente dell\u2019acqua,<\/h5>\n<p><a href=\"http:\/\/www.aipob-biodanza.org\/it_IT\/?attachment_id=2159\" rel=\"attachment wp-att-2159\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.aipob-biodanza.org\/wp-content\/uploads\/2019\/03\/aria-acqua-300x100.jpg\" alt=\"aria acqua\" width=\"300\" height=\"100\" class=\"alignnone size-medium wp-image-2159\" srcset=\"https:\/\/www.aipob-biodanza.org\/wp-content\/uploads\/2019\/03\/aria-acqua-300x100.jpg 300w, https:\/\/www.aipob-biodanza.org\/wp-content\/uploads\/2019\/03\/aria-acqua-768x256.jpg 768w, https:\/\/www.aipob-biodanza.org\/wp-content\/uploads\/2019\/03\/aria-acqua-1024x341.jpg 1024w, https:\/\/www.aipob-biodanza.org\/wp-content\/uploads\/2019\/03\/aria-acqua.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<h5>un percorso per nutrire e dare ali alle nostre idee<\/h5>\n<p>Carl Gustav Jung amava molto trascorrere del tempo vicino al lago scavando il terreno per creare certi piccoli rivoli d\u2019acqua.<\/p>\n<p>Ebbe modo di dire che quell\u2019attivit\u00e0, assieme allo starsene a guardare l\u2019acqua, costituiva per lui la migliore preparazione al lavoro creativo .<\/p>\n<p>Le idee affluivano a lui dall\u2019inconscio assai pi\u00f9 liberamente l\u00ec fuori che nella casa in cui si metteva poi a scrivere.<\/p>\n<h5>Quando<\/h5>\n<h6>il corso si tiene ogni\u00a0 mercoled\u00ec dalle ore 20,30 alle 22,30<\/h6>\n<h5>Dove<\/h5>\n<p>presso Epoch\u00e8 \u2013 Corso Lodi 65, Milano<\/p>\n<p>si consiglia abbigliamento comodo e calze di spugna o antiscivolo<\/p>\n<h5>PER INFORMAZIONI SUL CORSO<\/h5>\n<p>Antonella Bandini\u00a0 <a href=\"https:\/\/www.facebook.com\/antonella.bandini.12\">https:\/\/www.facebook.com\/antonella.bandini.12<\/a><\/p>\n<p>334 3765320\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 bandiniantonella@outlook.it<\/p>\n<p>Viviana Zavaglia\u00a0\u00a0\u00a0<a href=\"https:\/\/www.facebook.com\/search\/top\/?q=viviana%20zavaglia&amp;epa=SEARCH_BOX\">https:\/\/www.facebook.com\/search\/top\/?q=viviana%20zavaglia&amp;epa=SEARCH_BOX<\/a>\u00a0\u00a0\u00a0\u00a0\u00a0 338 8986531\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0viviana.vz@hotmail.it<\/p>\n<h5><\/h5>\n","protected":false},"excerpt":{"rendered":"<h1>Biodanza &#8211; corso settimanale<\/h1>\n<p><strong>Biodanza<\/strong>. \u00c8 il sistema ideato dallo psicologo, antropologo e poeta cileno Rolando Toro\u00a0<a href=\"http:\/\/www.aipob-biodanza.org\/it_IT\/rolando-toro\/\">http:\/\/www.aipob-biodanza.org\/it_IT\/rolando-tor&#8230;<\/p>\n","protected":false},"author":17,"featured_media":2159,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[14,11,54,43,81,82,55],"class_list":["post-2158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corsi-e-stage","tag-archetipi","tag-biodanza","tag-corso","tag-karl-gustav-jung","tag-milano","tag-quattro-elementi","tag-settimanale"],"_links":{"self":[{"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/posts\/2158"}],"collection":[{"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/comments?post=2158"}],"version-history":[{"count":11,"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/posts\/2158\/revisions"}],"predecessor-version":[{"id":2172,"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/posts\/2158\/revisions\/2172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/media\/2159"}],"wp:attachment":[{"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/media?parent=2158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/categories?post=2158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aipob-biodanza.org\/it_IT\/wp-json\/wp\/v2\/tags?post=2158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}